{"id":3839,"date":"2017-05-10T22:11:50","date_gmt":"2017-05-11T03:11:50","guid":{"rendered":"https:\/\/altemirconsulting.com\/inicio\/"},"modified":"2026-02-01T13:02:13","modified_gmt":"2026-02-01T19:02:13","slug":"inicio-old","status":"publish","type":"page","link":"https:\/\/altemirconsulting.com\/es\/inicio-old\/","title":{"rendered":"Inicio-OLD"},"content":{"rendered":"\n\n\t\t\t\t<a href=\"http:\/\/www.altemirconsulting.com\/lean-manufacturing\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/gears-1.png\" alt=\"lean manufacturing consultant\" itemprop=\"image\" height=\"75\" width=\"75\" title=\"Lean Manufacturing\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n<h3><a href=\"http:\/\/www.altemirconsulting.com\/lean-manufacturing\" target=\"_self\">Manufactura Lean<\/a><\/h3>\t\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-la-cadena-de-suministro\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/inventory.png\" alt=\"supply chain management consultant\" itemprop=\"image\" height=\"76\" width=\"75\" title=\"Supply Chain\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n<h3><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-la-cadena-de-suministro\/\" target=\"_self\">Cadena de Suministro<\/a><\/h3>\t\n\t\t\t\t<a href=\"http:\/\/www.altemirconsulting.com\/erp-mrp-mes\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/EnterpriseIT2.png\" alt=\"ERP consultant\" itemprop=\"image\" height=\"75\" width=\"75\" title=\"ERP\/Enterprise IT\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n<h3><a href=\"http:\/\/www.altemirconsulting.com\/erp-mrp-mes\/\" target=\"_self\">ERP \/ TI Empresarial<\/a><\/h3>\t\n\t\t\t\t<a href=\"http:\/\/www.altemirconsulting.com\/engineering\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.altemirconsulting.com\/wp-content\/uploads\/2019\/03\/engineering2.png\" alt=\"engineering consultant\" itemprop=\"image\" title=\"Engineering\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n<h3><a href=\"http:\/\/www.altemirconsulting.com\/engineering\" target=\"_self\">Ingenier\u00eda<\/a><\/h3>\t\n\t<h2>Desde la Planta de Producci\u00f3n Hasta la Sala de Juntas&#8230;<\/h2>\n<p>Desarrollamos e implementamos mejoras operativas para empresas de fabricaci\u00f3n y distribuci\u00f3n.<\/p>\n<p><strong>Asegurar la compra y la fabricaci\u00f3n a tiempo es nuestra especialidad<\/strong><\/p>\n<p>Prestamos nuestros servicios de asesoramiento durante la puesta en marcha, antes o despu\u00e9s de un evento de fusiones y adquisiciones, o como parte de una iniciativa de mejora continua o actualizaci\u00f3n del sistema.<\/p>\n<p>La direcci\u00f3n corporativa, el capital privado, los empresarios y las oficinas familiares de empresas de todos los tama\u00f1os recurren a nosotros para mejorar su rendimiento operativo y financiero y alcanzar objetivos estrat\u00e9gicos. Creemos en la b\u00fasqueda de mejoras transformadoras que sean permanentes y sostenibles. Evitamos soluciones provisionales incrementales que solo rozan la periferia de los verdaderos desaf\u00edos de su negocio.<\/p>\n\t\t\t<a href=\"https:\/\/calendly.com\/altemirconsulting\/30min\" target=\"_self\">\n\t\t\t\t\t\tProgramar una Llamada de Descubrimiento\n\t\t\t\t\t<\/a>\n<h2>\n\t\t\tAlgunos de nuestros \u00e9xitos pasados:\t<\/h2>\n\t<div class='white' style='background:rgba(0,0,0,0); border:solid 0px rgba(0,0,0,0); border-radius:0px; padding:0px 0px 0px 0px; overflow:hidden;'>\n<div id='slider_3484' class='owl-carousel sa_owl_theme autohide-arrows showcase_tablet showcase_hide_mobile' data-slider-id='slider_3484' style='visibility:hidden; width:120%; left:-10%; --widthtab:130%; --lefttab:-15%;'>\n<div id='slider_3484_slide01' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3503\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy01_v2.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy01_v2.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy01_v2-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy01_v2-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><\/div>\n<div id='slider_3484_slide02' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3504\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy02_v2.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy02_v2.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy02_v2-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy02_v2-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide03' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3505\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy03_v2.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy03_v2.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy03_v2-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy03_v2-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide04' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3526\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy04_v2.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy04_v2.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy04_v2-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy04_v2-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide05' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3492\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy05.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy05.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy05-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy05-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide06' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3493\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy06.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy06.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy06-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy06-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide07' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3494\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy07.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy07.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy07-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy07-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide08' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3495\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy08.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy08.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy08-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy08-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide09' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3496\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy09.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy09.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy09-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy09-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide10' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3497\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy10.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy10.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy10-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy10-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide11' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3498\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy11.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy11.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy11-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/03\/CaseStudy11-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide12' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3516\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/04\/CaseStudy12.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/04\/CaseStudy12.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/04\/CaseStudy12-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/04\/CaseStudy12-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide13' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3528 aligncenter\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy13.png\" alt=\"\" width=\"300\" height=\"256\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy13.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy13-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy13-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide14' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3529 aligncenter\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy14.png\" alt=\"\" width=\"300\" height=\"256\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy14.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy14-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2023\/08\/CaseStudy14-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide15' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3640\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy15.png\" alt=\"\" width=\"300\" height=\"255\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy15.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy15-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy15-100x85.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<div id='slider_3484_slide16' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3642\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy20_v2.png\" alt=\"\" width=\"300\" height=\"258\" srcset=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy20_v2.png 300w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy20_v2-50x43.png 50w, https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/05\/CaseStudy20_v2-100x86.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n<\/div>\n<div id='showcase_4338' class='showcase_nav owl-nav autohide_arrows'><\/div>\n<\/div>\n<script type='text\/javascript'>\n\tjQuery(document).ready(function() {\n\t\tjQuery('#slider_3484').owlCarousel({\n\t\t\tresponsive:{\n\t\t\t\t0:{ items:1 },\n\t\t\t\t480:{ items:2 },\n\t\t\t\t768:{ items:3 },\n\t\t\t\t980:{ items:4 },\n\t\t\t\t1200:{ items:4 },\n\t\t\t\t1500:{ items:5 }\n\t\t\t},\n\t\t\tautoplay : true,\n\t\t\tautoplayTimeout : 8000,\n\t\t\tautoplayHoverPause : true,\n\t\t\tsmartSpeed : 200,\n\t\t\tfluidSpeed : 200,\n\t\t\tautoplaySpeed : 200,\n\t\t\tnavSpeed : 200,\n\t\t\tdotsSpeed : 200,\n\t\t\tloop : true,\n\t\t\tnav : true,\n\t\t\tnavText : ['Previous','Next'],\n\t\t\tnavContainer : '#showcase_4338',\n\t\t\tdots : false,\n\t\t\tresponsiveRefreshRate : 200,\n\t\t\tslideBy : 2,\n\t\t\tmergeFit : true,\n\t\t\tautoHeight : false,\n\t\t\tmouseDrag : true,\n\t\t\ttouchDrag : true\n\t\t});\n\t\tjQuery('#slider_3484').css('visibility', 'visible');\n\t\tsa_resize_slider_3484();\n\t\twindow.addEventListener('resize', sa_resize_slider_3484);\n\t\tfunction sa_resize_slider_3484() {\n\t\t\tvar min_height = '50';\n\t\t\tvar win_width = jQuery(window).width();\n\t\t\tvar slider_width = jQuery('#slider_3484').width();\n\t\t\tif (win_width < 480) {\n\t\t\t\tvar slide_width = slider_width \/ 1;\n\t\t\t} else if (win_width < 768) {\n\t\t\t\tvar slide_width = slider_width \/ 2;\n\t\t\t} else if (win_width < 980) {\n\t\t\t\tvar slide_width = slider_width \/ 3;\n\t\t\t} else if (win_width < 1200) {\n\t\t\t\tvar slide_width = slider_width \/ 4;\n\t\t\t} else if (win_width < 1500) {\n\t\t\t\tvar slide_width = slider_width \/ 4;\n\t\t\t} else {\n\t\t\t\tvar slide_width = slider_width \/ 5;\n\t\t\t}\n\t\t\tslide_width = Math.round(slide_width);\n\t\t\tvar slide_height = '0';\n\t\t\tif (min_height == 'aspect43') {\n\t\t\t\tslide_height = (slide_width \/ 4) * 3;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else if (min_height == 'aspect169') {\n\t\t\t\tslide_height = (slide_width \/ 16) * 9;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else {\n\t\t\t\tslide_height = (slide_width \/ 100) * min_height;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t}\n\t\t\tjQuery('#slider_3484 .owl-item .sa_hover_container').css('min-height', slide_height+'px');\n\t\t}\n\t\tset_first_last_active_classes('slider_3484');\n\t\tjQuery('#slider_3484').on('translated.owl.carousel resized.owl.carousel', function(event) {\n\t\t\tset_first_last_active_classes('slider_3484');\n\t\t});\n\t\tfunction set_first_last_active_classes(css_id) {\n\t\t\tvar total = jQuery('#slider_3484 .owl-stage .owl-item.active').length;\n\t\t\tjQuery('#slider_3484 .owl-stage .owl-item').removeClass('sc_partial');\n\t\t\tjQuery('#slider_3484 .owl-stage .owl-item.active').each(function(index){\n\t\t\t\tif (index === 0) {\n\t\t\t\t\tjQuery(this).addClass('sc_partial');\n\t\t\t\t}\n\t\t\t\tif (index === total - 1 && total > 1) {\n\t\t\t\t\tjQuery(this).addClass('sc_partial');\n\t\t\t\t}\n\t\t\t});\n\t\t}\n\t\tvar owl_goto = jQuery('#slider_3484');\n\t\tjQuery('.slider_3484_goto1').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 0);\n\t\t});\n\t\tjQuery('.slider_3484_goto2').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 1);\n\t\t});\n\t\tjQuery('.slider_3484_goto3').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 2);\n\t\t});\n\t\tjQuery('.slider_3484_goto4').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 3);\n\t\t});\n\t\tjQuery('.slider_3484_goto5').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 4);\n\t\t});\n\t\tjQuery('.slider_3484_goto6').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 5);\n\t\t});\n\t\tjQuery('.slider_3484_goto7').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 6);\n\t\t});\n\t\tjQuery('.slider_3484_goto8').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 7);\n\t\t});\n\t\tjQuery('.slider_3484_goto9').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 8);\n\t\t});\n\t\tjQuery('.slider_3484_goto10').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 9);\n\t\t});\n\t\tjQuery('.slider_3484_goto11').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 10);\n\t\t});\n\t\tjQuery('.slider_3484_goto12').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 11);\n\t\t});\n\t\tjQuery('.slider_3484_goto13').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 12);\n\t\t});\n\t\tjQuery('.slider_3484_goto14').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 13);\n\t\t});\n\t\tjQuery('.slider_3484_goto15').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 14);\n\t\t});\n\t\tjQuery('.slider_3484_goto16').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 15);\n\t\t});\n\t\tvar resize_4338 = jQuery('.owl-carousel');\n\t\tresize_4338.on('initialized.owl.carousel', function(e) {\n\t\t\tif (typeof(Event) === 'function') {\n\t\t\t\twindow.dispatchEvent(new Event('resize'));\n\t\t\t} else {\n\t\t\t\tvar evt = window.document.createEvent('UIEvents');\n\t\t\t\tevt.initUIEvent('resize', true, false, window, 0);\n\t\t\t\twindow.dispatchEvent(evt);\n\t\t\t}\n\t\t});\n\t});\n<\/script>\n\n\t<h3><strong>\u00c1REAS DE ENFOQUE<\/strong><\/h3>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/fabricacion-ajustada\/\">Lean Manufacturing<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-la-cadena-de-suministro\/\">Gesti\u00f3n de la Cadena de Suministro<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/erp-mrp-mes-aps\/\">ERP y TI Empresarial<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/ingenieria\/\">Ingenier\u00eda<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/garantia-de-calidad\/\">Garant\u00eda de Calidad<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/almacenamiento\/\">Almacenamiento y Distribuci\u00f3n<\/a><\/p>\n\t<h3><strong>SECTORES<\/strong><\/h3>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/sector-aeroespacial-y-de-defensa\/\">Aeroespacial y Defensa<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/dispositivos-medicos\/\">Dispositivos M\u00e9dicos<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/fabricacion-ajustada\/\">Fabricaci\u00f3n por Contrato<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/sectores\/\">Equipos Industriales<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/fabricacion-de-alimentos\/\">Fabricaci\u00f3n de Alimentos<\/a><\/p>\n<p><a href=\"https:\/\/www.altemirconsulting.com\/industries\/\">Productos de Consumo<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/sectores\/\">Otros Tipos de Fabricaci\u00f3n Discreta<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-inventario\/\">Almacenamiento y Distribuci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/sectores\/\">Startups<\/a><\/p>\n\t<h3><strong>ESPECIALIDADES<\/strong><\/h3>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/fabricacion-ajustada\/\">Lean Manufacturing<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/optimizacion-de-erp\/\">Optimizaci\u00f3n de ERP<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/programacion-de-la-produccion-de-fabricacion\/\">Planificaci\u00f3n y Programaci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-la-cadena-de-suministro\/\">Gesti\u00f3n de la Cadena de Suministro<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-inventario\/\">Gesti\u00f3n de Inventario<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\">Reestructuraciones Operativas<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/almacenamiento\/\">Almacenamiento y Distribuci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/www.altemirconsulting.com\/sales-operations-planning-siop\/\">Planificaci\u00f3n Estrat\u00e9gica )SIOP \/ S&amp;OP)<\/a><\/p>\n<p><a href=\"https:\/\/www.altemirconsulting.com\/quality-assurance-consulting\/\">Seguro de Calidad<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/especialidades\/\">Introducci\u00f3n de Nuevos Productos<\/a><\/p>\n<p><a href=\"https:\/\/altemirconsulting.com\/es\/gerencia-interina\/\">Gerencia Interina<\/a><\/p>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\" target=\"_self\">90 D\u00edas Para la Ejecuci\u00f3n a Tiempo<\/a><\/h3><p>Nuestro programa <em>90 d\u00edas para la ejecuci\u00f3n a tiempo<\/em> ofrece muchos de nuestros servicios de asesoramiento principales como un compromiso personalizado de 90 d\u00edas para ayudar a los fabricantes a lograr un rendimiento a tiempo en toda su cadena de suministro. Trabajamos con su equipo para establecer una planificaci\u00f3n, programaci\u00f3n y control de la producci\u00f3n eficaces utilizando su sistema ERP existente para garantizar que su operaci\u00f3n sea sistem\u00e1ticamente puntual, est\u00e9 orientada al cliente y sea rentable.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2021\/05\/Factory_136368784-aerial-top-view-industrial-sto.jpeg\" alt=\"Aerial Top View of Industrial Storage Building Area with Solar Panels on the Roof and Many Trucks Unloading Merchandise.\" itemprop=\"image\" height=\"169\" width=\"300\" title=\"Aerial Top View of Industrial Storage Building Area with Solar P\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/erp-mrp-mes-aps\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/04\/software-1-300x169.jpg\" alt=\"cleaning up ERP data\" itemprop=\"image\" height=\"169\" width=\"300\" title=\"erp data remediation\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/erp-mrp-mes-aps\/\" target=\"_self\">ERP y Transformaci\u00f3n Digital<\/a><\/h3><p>Los clientes del siglo XXI y la competencia del mercado exigen una superioridad informativa. Proporcionamos selecci\u00f3n, implementaci\u00f3n y optimizaci\u00f3n de sistemas para ERP, MES, PLM y tecnolog\u00edas de TI relacionadas, desde la estrategia de nivel superior hasta la experiencia t\u00e9cnica pr\u00e1ctica. Tambi\u00e9n podemos ayudar a su empresa a abrirse camino con tecnolog\u00edas digitales de vanguardia.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/erp-mrp-mes-aps\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-inventario\/\" target=\"_self\">Optimizaci\u00f3n del Inventario<\/a><\/h3><p>Consiga que su inventario trabaje para usted, no en su contra. Altemir Consulting ayuda a los fabricantes a dimensionar correctamente su inventario para eliminar la escasez y evitar el exceso de existencias, lo que a menudo impulsa una reducci\u00f3n neta del inventario. Tambi\u00e9n reforzamos la precisi\u00f3n y el control del inventario para que su sistema sea fiable, las compras sean eficientes y sus costes sean correctos. Visite nuestra p\u00e1gina de Gesti\u00f3n de inventario para saber c\u00f3mo podemos mejorar su planificaci\u00f3n de inventario, la ejecuci\u00f3n de las compras y el control del almac\u00e9n.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-inventario\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/gestion-de-inventario\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/04\/performance-improvement-300x169.jpg\" alt=\"performance improvement\" itemprop=\"image\" height=\"169\" width=\"300\" title=\"performance-improvement\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2025\/12\/WorkBench-300x172.jpg\" alt=\"WorkBench\" itemprop=\"image\" height=\"172\" width=\"300\" title=\"WorkBench\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\" target=\"_self\">Reducci\u00f3n de la Cartera de Pedidos Vencidos<\/a><\/h3><p>\u00a1Somos los expertos en rendimiento a tiempo! Podemos trabajar en todo su proceso de cumplimiento de pedidos para identificar y resolver los cuellos de botella de planificaci\u00f3n y ejecuci\u00f3n que impulsan las carteras de pedidos vencidos. Podemos formular una estrategia integral e implementar las mejoras t\u00e1cticas para eliminar las carteras de pedidos vencidos y optimizar su capacidad de producci\u00f3n para cumplir y mantener los compromisos con los clientes de forma fiable.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/90-dias-para-la-ejecucion-a-tiempo\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/programacion-de-la-produccion-de-fabricacion\/\" target=\"_self\">Planificaci\u00f3n y Programaci\u00f3n de la Producci\u00f3n<\/a><\/h3><p>Somos los expertos en planificaci\u00f3n y programaci\u00f3n avanzadas (APS) de ERP. Nuestro enfoque \u00fanico para establecer un sistema de control de la producci\u00f3n estable y eficaz no tiene parang\u00f3n a la hora de cumplir sus objetivos empresariales de una forma que otros consultores y proveedores de software no lo hacen. Descubra por qu\u00e9 nuestro enfoque es fundamentalmente diferente y puede marcar una diferencia transformadora positiva en su operaci\u00f3n.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/programacion-de-la-produccion-de-fabricacion\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/programacion-de-la-produccion-de-fabricacion\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/04\/planning-300x168.jpg\" alt=\"manufacturing planning\" itemprop=\"image\" height=\"168\" width=\"300\" title=\"planning\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/lean-mrp\/\"  target=\"_self\" itemprop=\"url\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/04\/welder-400-300x169.jpg\" alt=\"lean manufacturing\" itemprop=\"image\" height=\"169\" width=\"300\" title=\"welder-400\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<\/a>\n\t\t<h3><a href=\"https:\/\/altemirconsulting.com\/es\/lean-mrp\/\" target=\"_self\">Lean Shop Floor y Cadena de Suministro<\/a><\/h3><p>Adem\u00e1s de nuestra experiencia en la mejora de procesos lean y la gesti\u00f3n de materiales, tambi\u00e9n somos los innovadores de la metodolog\u00eda de control de planta <a href=\"https:\/\/altemirconsulting.com\/es\/lean-mrp\/\">Lean MRP<\/a> que le permite establecer un sistema de extracci\u00f3n Lean en la planta utilizando su sistema ERP existente. Este es un enfoque novedoso y eficaz que puede marcar una diferencia dr\u00e1stica para los fabricantes que se enfrentan a profundas listas de materiales en un entorno de taller de trabajo.<\/p>\n\t\t\t<a href=\"https:\/\/altemirconsulting.com\/es\/lean-mrp\/\" target=\"_self\">\n\t\t\t\t\t\t\tM\u00e1s Informaci\u00f3n\n\t\t\t\t\t<\/a>\n\t\t<h3>Iniciativas Estrat\u00e9gicas<\/h3><p>Podemos ampliar instant\u00e1neamente las capacidades de su equipo proporcionando recursos clave para liderar o apoyar iniciativas clave. La introducci\u00f3n de nuevos productos (NPI), la planificaci\u00f3n de inventario y operaciones de ventas (SIOP\/S&amp;OP), el dise\u00f1o para la fabricaci\u00f3n (DFM), las transiciones de instalaciones y las racionalizaciones de la cadena de suministro son solo algunos ejemplos de d\u00f3nde podemos proporcionar liderazgo y apoyo.<\/p>\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/04\/SpecialProjects-300x169.jpg\" alt=\"SpecialProjects\" itemprop=\"image\" height=\"169\" width=\"300\" title=\"SpecialProjects\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t<a href=\"https:\/\/calendly.com\/altemirconsulting\/30min\" target=\"_self\">\n\t\t\t\t\t\tProgramar una Llamada de Descubrimiento\n\t\t\t\t\t<\/a>\n\t\t<h3>Explore las Posibilidades&#8230;<\/h3>\n\t\t<p>Agradecemos las consultas de todas las empresas, peque\u00f1as y grandes, que est\u00e9n ansiosas por pasar al siguiente nivel. No dude en ponerse en contacto con nosotros para hablar de sus necesidades espec\u00edficas sin compromiso.<\/p>\n\t\t\t<a href=\"https:\/\/www.altemirconsulting.com\/contact-us\" target=\"_self\">\n\t\t\t\t\t\t\tCont\u00e1ctenos\n\t\t\t\t\t<\/a>\n\n","protected":false},"excerpt":{"rendered":"<p>Manufactura Lean Cadena de Suministro ERP \/ TI Empresarial Ingenier\u00eda Desde la Planta de Producci\u00f3n Hasta la Sala de Juntas&#8230; Desarrollamos e implementamos mejoras operativas para empresas de fabricaci\u00f3n y distribuci\u00f3n. Asegurar la compra y la fabricaci\u00f3n a tiempo es nuestra especialidad Prestamos nuestros servicios de asesoramiento durante la puesta en marcha, antes o despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-3839","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Altemir Consulting | Lean Manufacturing, Cadena de Suministro y ERP<\/title>\n<meta name=\"description\" content=\"Ayudamos a los fabricantes a materializar mejoras operativas y objetivos estrat\u00e9gicos desde la planta de producci\u00f3n hasta la sala de juntas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/altemirconsulting.com\/es\/inicio-old\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/\",\"url\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/\",\"name\":\"Altemir Consulting | Lean Manufacturing, Cadena de Suministro y ERP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altemirconsulting.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/gears-1.png\",\"datePublished\":\"2017-05-11T03:11:50+00:00\",\"dateModified\":\"2026-02-01T19:02:13+00:00\",\"description\":\"Ayudamos a los fabricantes a materializar mejoras operativas y objetivos estrat\u00e9gicos desde la planta de producci\u00f3n hasta la sala de juntas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/#primaryimage\",\"url\":\"https:\\\/\\\/altemirconsulting.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/gears-1.png\",\"contentUrl\":\"https:\\\/\\\/altemirconsulting.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/gears-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/inicio-old\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio-OLD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/\",\"name\":\"Altemir Consulting\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#organization\",\"name\":\"Altemir Consulting\",\"url\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/altemirconsulting.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/altemirconsulting.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/favicon.png\",\"width\":300,\"height\":300,\"caption\":\"Altemir Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/altemirconsulting.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AltemirConsulting\\\/\",\"https:\\\/\\\/x.com\\\/AltemirConsult\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/altemirconsulting\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCymlsqpZMZn-GlEFli_bnfA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Altemir Consulting | Lean Manufacturing, Cadena de Suministro y ERP","description":"Ayudamos a los fabricantes a materializar mejoras operativas y objetivos estrat\u00e9gicos desde la planta de producci\u00f3n hasta la sala de juntas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/altemirconsulting.com\/es\/inicio-old\/","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/","url":"https:\/\/altemirconsulting.com\/es\/inicio-old\/","name":"Altemir Consulting | Lean Manufacturing, Cadena de Suministro y ERP","isPartOf":{"@id":"https:\/\/altemirconsulting.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/#primaryimage"},"image":{"@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/#primaryimage"},"thumbnailUrl":"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/gears-1.png","datePublished":"2017-05-11T03:11:50+00:00","dateModified":"2026-02-01T19:02:13+00:00","description":"Ayudamos a los fabricantes a materializar mejoras operativas y objetivos estrat\u00e9gicos desde la planta de producci\u00f3n hasta la sala de juntas.","breadcrumb":{"@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/altemirconsulting.com\/es\/inicio-old\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/#primaryimage","url":"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/gears-1.png","contentUrl":"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2019\/03\/gears-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/altemirconsulting.com\/es\/inicio-old\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/altemirconsulting.com\/es\/"},{"@type":"ListItem","position":2,"name":"Inicio-OLD"}]},{"@type":"WebSite","@id":"https:\/\/altemirconsulting.com\/es\/#website","url":"https:\/\/altemirconsulting.com\/es\/","name":"Altemir Consulting","description":"","publisher":{"@id":"https:\/\/altemirconsulting.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/altemirconsulting.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/altemirconsulting.com\/es\/#organization","name":"Altemir Consulting","url":"https:\/\/altemirconsulting.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/altemirconsulting.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2017\/09\/favicon.png","contentUrl":"https:\/\/altemirconsulting.com\/wp-content\/uploads\/2017\/09\/favicon.png","width":300,"height":300,"caption":"Altemir Consulting"},"image":{"@id":"https:\/\/altemirconsulting.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AltemirConsulting\/","https:\/\/x.com\/AltemirConsult","https:\/\/www.linkedin.com\/company\/altemirconsulting\/","https:\/\/www.youtube.com\/channel\/UCymlsqpZMZn-GlEFli_bnfA"]}]}},"_links":{"self":[{"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/pages\/3839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/comments?post=3839"}],"version-history":[{"count":8,"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/pages\/3839\/revisions"}],"predecessor-version":[{"id":4688,"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/pages\/3839\/revisions\/4688"}],"wp:attachment":[{"href":"https:\/\/altemirconsulting.com\/es\/wp-json\/wp\/v2\/media?parent=3839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}